{"id":2360,"date":"2026-07-13T04:17:54","date_gmt":"2026-07-13T04:17:54","guid":{"rendered":"https:\/\/openschool.ac.th\/?page_id=2360"},"modified":"2026-07-13T04:36:57","modified_gmt":"2026-07-13T04:36:57","slug":"elementor-2360","status":"publish","type":"page","link":"https:\/\/openschool.ac.th\/en\/elementor-2360\/","title":{"rendered":""},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2360\" class=\"elementor elementor-2360\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abf906f e-con-full e-flex e-con e-parent\" data-id=\"abf906f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2362,&quot;url&quot;:&quot;https:\\\/\\\/openschool.ac.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bgTop.png&quot;}],&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce2f2df elementor-widget elementor-widget-spacer\" data-id=\"ce2f2df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6c8725 elementor-widget elementor-widget-image\" data-id=\"d6c8725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"519\" height=\"96\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/logo.png\" class=\"attachment-large size-large wp-image-2364\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/logo.png 519w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/logo-300x55.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/logo-18x3.png 18w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c59ac62 elementor-widget elementor-widget-image\" data-id=\"c59ac62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"851\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-963x1024.png\" class=\"attachment-large size-large wp-image-2363\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-963x1024.png 963w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-282x300.png 282w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-768x817.png 768w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-1444x1536.png 1444w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head-11x12.png 11w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/head.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbfe47d e-flex e-con-boxed e-con e-parent\" data-id=\"cbfe47d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f90b6f3 elementor-widget elementor-widget-image\" data-id=\"f90b6f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"189\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner-1024x242.png\" class=\"attachment-large size-large wp-image-2366\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner-1024x242.png 1024w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner-300x71.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner-768x181.png 768w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner-18x4.png 18w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/partner.png 1293w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ffd051 e-flex e-con-boxed e-con e-parent\" data-id=\"1ffd051\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e39ff23 elementor-widget elementor-widget-image\" data-id=\"e39ff23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"430\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic-1024x551.png\" class=\"attachment-large size-large wp-image-2367\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic-1024x551.png 1024w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic-300x161.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic-768x413.png 768w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic-18x10.png 18w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academic.png 1293w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-286fd6f e-flex e-con-boxed e-con e-parent\" data-id=\"286fd6f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-224a005 elementor-widget elementor-widget-image\" data-id=\"224a005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"876\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HNC.png\" class=\"attachment-large size-large wp-image-2368\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HNC.png 634w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HNC-217x300.png 217w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HNC-9x12.png 9w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5596e70 elementor-widget elementor-widget-image\" data-id=\"5596e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"876\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HND.png\" class=\"attachment-large size-large wp-image-2369\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HND.png 634w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HND-217x300.png 217w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/HND-9x12.png 9w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccc9c4f e-flex e-con-boxed e-con e-parent\" data-id=\"ccc9c4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3db12c elementor-widget elementor-widget-image\" data-id=\"c3db12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"44\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academicRemark.png\" class=\"attachment-large size-large wp-image-2370\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academicRemark.png 854w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academicRemark-300x17.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academicRemark-768x42.png 768w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/academicRemark-18x1.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f40b64 elementor-widget elementor-widget-spacer\" data-id=\"8f40b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64e748a e-con-full e-flex e-con e-parent\" data-id=\"64e748a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2371,&quot;url&quot;:&quot;https:\\\/\\\/openschool.ac.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bgBottom.png&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t<div class=\"elementor-element elementor-element-f5f5bed e-con-full e-flex e-con e-child\" data-id=\"f5f5bed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2372,&quot;url&quot;:&quot;https:\\\/\\\/openschool.ac.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/bg2-yLayer-1.png&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7324762 elementor-widget elementor-widget-image\" data-id=\"7324762\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"455\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/experience.png\" class=\"attachment-large size-large wp-image-2373\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/experience.png 585w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/experience-300x233.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/experience-15x12.png 15w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c75a4e2 elementor-widget elementor-widget-image\" data-id=\"c75a4e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"557\" height=\"458\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/student.png\" class=\"attachment-large size-large wp-image-2374\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/student.png 557w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/student-300x247.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/student-15x12.png 15w\" sizes=\"(max-width: 557px) 100vw, 557px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f417f1e elementor-widget elementor-widget-spacer\" data-id=\"f417f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a197ca elementor-widget elementor-widget-image\" data-id=\"3a197ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"76\" src=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply-1024x97.png\" class=\"attachment-large size-large wp-image-2375\" alt=\"\" srcset=\"https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply-1024x97.png 1024w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply-300x28.png 300w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply-768x73.png 768w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply-18x2.png 18w, https:\/\/openschool.ac.th\/wp-content\/uploads\/2026\/07\/apply.png 1074w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e5123 elementor-widget elementor-widget-spacer\" data-id=\"81e5123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2360","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/pages\/2360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":17,"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/pages\/2360\/revisions"}],"predecessor-version":[{"id":2393,"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/pages\/2360\/revisions\/2393"}],"wp:attachment":[{"href":"https:\/\/openschool.ac.th\/en\/wp-json\/wp\/v2\/media?parent=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}